{"id":1425,"date":"2024-06-01T16:51:14","date_gmt":"2024-06-01T14:51:14","guid":{"rendered":"https:\/\/new.ptsv-rosenheim.de\/?page_id=1425"},"modified":"2024-09-20T07:51:54","modified_gmt":"2024-09-20T05:51:54","slug":"news-laufabteilung","status":"publish","type":"page","link":"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/","title":{"rendered":"News Laufabteilung"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1425\" class=\"elementor elementor-1425\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3cc2030f e-con-full e-flex e-con e-parent\" data-id=\"3cc2030f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7f3efdb6 e-con-full e-flex e-con e-child\" data-id=\"7f3efdb6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;shape_divider_top&quot;:&quot;waves&quot;,&quot;shape_divider_bottom&quot;:&quot;waves&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M421.9,6.5c22.6-2.5,51.5,0.4,75.5,5.3c23.6,4.9,70.9,23.5,100.5,35.7c75.8,32.2,133.7,44.5,192.6,49.7\n\tc23.6,2.1,48.7,3.5,103.4-2.5c54.7-6,106.2-25.6,106.2-25.6V0H0v30.3c0,0,72,32.6,158.4,30.5c39.2-0.7,92.8-6.7,134-22.4\n\tc21.2-8.1,52.2-18.2,79.7-24.2C399.3,7.9,411.6,7.5,421.9,6.5z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M790.5,93.1c-59.3-5.3-116.8-18-192.6-50c-29.6-12.7-76.9-31-100.5-35.9c-23.6-4.9-52.6-7.8-75.5-5.3\n\tc-10.2,1.1-22.6,1.4-50.1,7.4c-27.2,6.3-58.2,16.6-79.4,24.7c-41.3,15.9-94.9,21.9-134,22.6C72,58.2,0,25.8,0,25.8V100h1000V65.3\n\tc0,0-51.5,19.4-106.2,25.7C839.5,97,814.1,95.2,790.5,93.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6154dbb e-con-full e-flex e-con e-child\" data-id=\"6154dbb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c616682 elementor-widget__width-inherit elementor-widget-tablet__width-inherit elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4c616682\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">News<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-95ec4b0 e-con-full e-flex e-con e-child\" data-id=\"95ec4b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5702309 elementor-widget-tablet__width-initial elementor-widget elementor-widget-ucaddon_post_list\" data-id=\"5702309\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_post_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Post List -->\n\t\t<link id='font-awesome-css' href='https:\/\/ptsv-rosenheim.de\/wp-content\/plugins\/unlimited-elements-for-elementor\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/ptsv-rosenheim.de\/wp-content\/plugins\/unlimited-elements-for-elementor\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Post List *\/\n\n\n\n#uc_post_list_elementor_5702309{\n  display:grid;\n}\n\n#uc_post_list_elementor_5702309 .uc_post_list_image div{\n  background-size:cover;\n  background-position:center;\n}\n\n.uc_post_list .uc_post_list_box{\n\tposition: relative;\n\toverflow: hidden;\n\tdisplay: flex;\n}\n\n#uc_post_list_elementor_5702309 .uc_post_list_image{\n  flex-grow:0;\n  flex-shrink:0;\n  overflow: hidden;\n}\n\n#uc_post_list_elementor_5702309 .uc_post_list_image img{\n  width:100%;\n  height:100%;\n  display:block;\n  transition:0.3s;  \n}\n\n.uc_post_list_title a{\n\tcolor: #333333;\n    display: block;\n}\n\n.uc_post_list_date{\n\tfont-size: 12px;\n}\n\n#uc_post_list_elementor_5702309 .uc_post_list_content{\n  display:flex;\n  flex-direction:column;\n  flex:1;\n}\n\n#uc_post_list_elementor_5702309 .uc_more_btn{\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n#uc_post_list_elementor_5702309 .button-on-side{\n  display:flex;\n  align-items:center;\n}\n\n#uc_post_list_elementor_5702309 .ue-grid-item-category{\n  display: flex;\n  align-items: center;\n}\n\n.ue-grid-item-category a{\n  display:inline-block;\n  font-size:10px;\n  text-transform:uppercase;\n}\n\n#uc_post_list_elementor_5702309 .ue-meta-data{  \n  display:flex;\n  flex-wrap: wrap;\n  line-height:1em;\n}\n\n#uc_post_list_elementor_5702309 .ue-grid-item-meta-data{\n      display:inline-flex;\n      align-items:center;\n}\n\n.ue-grid-item-meta-data{\n  font-size:12px;\n}\n\n#uc_post_list_elementor_5702309 .ue-grid-item-meta-data-icon{\n  line-height:1em;\n}\n\n#uc_post_list_elementor_5702309 .ue-grid-item-meta-data-icon svg{\n  width:1em;\n  height:1em;\n} \n\n#uc_post_list_elementor_5702309 .ue-debug-meta{\n  padding:10px;\n  border:1px solid red;\n  position:relative;\n  line-height:1.5em;\n  font-size:11px;\n  width:100%;\n}\n\n.uc-remote-parent .uc_post_list_box{\n\tcursor:pointer;\n}\n\n#uc_post_list_elementor_5702309 .ue-post-link-overlay{\n  display:block;\n  position:absolute;\n  top:0;\n  bottom:0;\n  right:0;\n  left:0;\n}\n\n\n\n\n<\/style>\n\n<div class=\"uc_post_list uc-items-wrapper uc-filterable-grid \" id=\"uc_post_list_elementor_5702309\"  data-ajax='true'  data-filterbehave='ajax'  querydata='{&quot;count_posts&quot;:4,&quot;total_posts&quot;:58,&quot;page&quot;:1,&quot;num_pages&quot;:15}' >    \t\n  <div class=\"uc_post_list_box\" data-category=\"Beitr\u00e4ge Allgemein\">\n\n  \n  \t    <div class=\"uc_post_list_image\">\n      <a href=\"https:\/\/ptsv-rosenheim.de\/index.php\/2026\/07\/29\/erfolge-beim-holiday-meeting-leichtathletikabend\/\" target=\"_self\" title=\"Erfolge beim Holiday Meeting Leichtathletikabend\">\n          \n            <img decoding=\"async\" src=\"https:\/\/ptsv-rosenheim.de\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-30-at-20.53.38-768x576.jpeg\"  src=\"https:\/\/ptsv-rosenheim.de\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-30-at-20.53.38-768x576.jpeg\" alt=\"WhatsApp Image 2026-07-30 at 20.53\" width=\"768\" height=\"576\">\n        \t\n        \n      <\/a>\n    <\/div>\n  \t\t\n  \n    <div class=\"uc_post_list_content\">\n      <div class=\"uc_post_list_content_inside\">\n        \n                       \n        <div class=\"uc_post_list_title\"><a target=\"_self\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/2026\/07\/29\/erfolge-beim-holiday-meeting-leichtathletikabend\/\" title=\"Erfolge beim Holiday Meeting Leichtathletikabend\">Erfolge beim Holiday Meeting Leichtathletikabend<\/a><\/div>                 \n        <div class=\"ue-meta-data\">\n                                               \n            \n          \n                        \n            \n                        \n                        \n            \n              \n          <\/div>         \n                \n         <div class=\"uc_post_content\">29. Juli 2026\n\n\nDer Holiday Meeting Leichtathletikabend im Dantestadion M\u00fcnchen war f\u00fcr die Jugend des PTSV Rosenheim ein besonderes Erlebnis. Bei sommerlichen 34 Grad traten die jungen Athletinnen und...<\/div>           \n        \n                 \n      <\/div>\n    <\/div>\n     \n       \n  \n   <\/div>\n<div class=\"uc_post_list_box\" data-category=\"Beitr\u00e4ge Allgemein\">\n\n  \n  \t    <div class=\"uc_post_list_image\">\n      <a href=\"https:\/\/ptsv-rosenheim.de\/index.php\/2026\/07\/03\/5x-gold-bei-der-berglauf-wm\/\" target=\"_self\" title=\"5x Gold bei der Berglauf Masters-WM\">\n          \n            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ptsv-rosenheim.de\/wp-content\/uploads\/2026\/07\/Wini-Huber.jpeg\"  src=\"https:\/\/ptsv-rosenheim.de\/wp-content\/uploads\/2026\/07\/Wini-Huber.jpeg\" alt=\"Wini-Huber\" width=\"739\" height=\"1600\">\n        \t\n        \n      <\/a>\n    <\/div>\n  \t\t\n  \n    <div class=\"uc_post_list_content\">\n      <div class=\"uc_post_list_content_inside\">\n        \n                       \n        <div class=\"uc_post_list_title\"><a target=\"_self\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/2026\/07\/03\/5x-gold-bei-der-berglauf-wm\/\" title=\"5x Gold bei der Berglauf Masters-WM\">5x Gold bei der Berglauf Masters-WM<\/a><\/div>                 \n        <div class=\"ue-meta-data\">\n                                               \n            \n          \n                        \n            \n                        \n                        \n            \n              \n          <\/div>         \n                \n         <div class=\"uc_post_content\">106 deutsche Masters-Athletinnen und -Athleten hatten sich f\u00fcr die Berg- und Traillauf-WM im tschechischen Jansk\u00e9 L\u00e1zn\u0115 (deutsch: Johannisbad) im Riesengebirge angemeldet. Die \u201eWorld Masters Mountain Running...<\/div>           \n        \n                 \n      <\/div>\n    <\/div>\n     \n       \n  \n   <\/div>\n<div class=\"uc_post_list_box\" data-category=\"Beitr\u00e4ge Allgemein\">\n\n  \n  \t    <div class=\"uc_post_list_image\">\n      <a href=\"https:\/\/ptsv-rosenheim.de\/index.php\/2026\/06\/22\/rosenheim-im-rahmen-der-staedtepartnerschaft-empfing-der-ptsv-rosenheim-am-vergangenen-wochenende-eine-delegation-des-amateursportvereins-le-sgalmare-aus-dem-italienischen\/\" target=\"_self\" title=\"Rosenheim \u2013 Im Rahmen der St\u00e4dtepartnerschaft empfing der PTSV Rosenheim am vergangenen Wochenende eine Delegation des Amateursportvereins \u201eLe Sgalmare\u201c aus dem italienischen Partnerort Col\u00e0 (Lazise).\">\n          \n            <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ptsv-rosenheim.de\/wp-content\/uploads\/2026\/06\/20260620_205732-768x458.jpg\"  src=\"https:\/\/ptsv-rosenheim.de\/wp-content\/uploads\/2026\/06\/20260620_205732-768x458.jpg\" alt=\"20260620_205732\" width=\"768\" height=\"458\">\n        \t\n        \n      <\/a>\n    <\/div>\n  \t\t\n  \n    <div class=\"uc_post_list_content\">\n      <div class=\"uc_post_list_content_inside\">\n        \n                       \n        <div class=\"uc_post_list_title\"><a target=\"_self\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/2026\/06\/22\/rosenheim-im-rahmen-der-staedtepartnerschaft-empfing-der-ptsv-rosenheim-am-vergangenen-wochenende-eine-delegation-des-amateursportvereins-le-sgalmare-aus-dem-italienischen\/\" title=\"Rosenheim \u2013 Im Rahmen der St\u00e4dtepartnerschaft empfing der PTSV Rosenheim am vergangenen Wochenende eine Delegation des Amateursportvereins \u201eLe Sgalmare\u201c aus dem italienischen Partnerort Col\u00e0 (Lazise).\">Rosenheim \u2013 Im Rahmen der St\u00e4dtepartnerschaft empfing der PTSV Rosenheim am vergangenen Wochenende eine Delegation des Amateursportvereins \u201eLe Sgalmare\u201c aus dem italienischen Partnerort Col\u00e0 (Lazise).<\/a><\/div>                 \n        <div class=\"ue-meta-data\">\n                                               \n            \n          \n                        \n            \n                        \n                        \n            \n              \n          <\/div>         \n                \n         <div class=\"uc_post_content\">Bei sommerlichen Temperaturen bewirtete das PTSV-Team die G\u00e4ste auf dem Vereinsgel\u00e4nde. An dem geselligen Austausch nahmen auch Rosenheims 2. B\u00fcrgermeister Daniel Artmann und die 3. B\u00fcrgermeisterin Gabriele...<\/div>           \n        \n                 \n      <\/div>\n    <\/div>\n     \n       \n  \n   <\/div>\n<div class=\"uc_post_list_box\" data-category=\"Beitr\u00e4ge Allgemein\">\n\n  \n  \t    <div class=\"uc_post_list_image\">\n      <a href=\"https:\/\/ptsv-rosenheim.de\/index.php\/2026\/06\/10\/bayerischer-rekord-5000m-julika-fidjeland-laeuft-215537\/\" target=\"_self\" title=\"Bayerischer Rekord 5000m - Julika Fidjeland l\u00e4uft 21:55,37\">\n                     <img decoding=\"async\" src=\"https:\/\/ptsv-rosenheim.de\/wp-content\/uploads\/ac_assets\/uc_post_list\/\/placeholder.jpeg\">\n        \t\n        \n      <\/a>\n    <\/div>\n  \t\t\n  \n    <div class=\"uc_post_list_content\">\n      <div class=\"uc_post_list_content_inside\">\n        \n                       \n        <div class=\"uc_post_list_title\"><a target=\"_self\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/2026\/06\/10\/bayerischer-rekord-5000m-julika-fidjeland-laeuft-215537\/\" title=\"Bayerischer Rekord 5000m - Julika Fidjeland l\u00e4uft 21:55,37\">Bayerischer Rekord 5000m - Julika Fidjeland l\u00e4uft 21:55,37<\/a><\/div>                 \n        <div class=\"ue-meta-data\">\n                                               \n            \n          \n                        \n            \n                        \n                        \n            \n              \n          <\/div>         \n                \n         <div class=\"uc_post_content\">Beim Meeting am 10.06.2026 in Karlsfeld l\u00e4uft Julika Fidjeland den Bayerischen W65 Rekord. Mit ihrer Zeit von 21:55,37 auf die 12,5 Stadionrunden verbessert sie den 20 Jahre alten Rekord von Barbara Wolf...<\/div>           \n        \n                 \n      <\/div>\n    <\/div>\n     \n       \n  \n   <\/div>\n\n<\/div>\n\n\n  <div id=\"uc_post_list_elementor_5702309_empty_message\" class=\"ue-no-posts-found\"  style=\"display:none\" >No posts found<\/div>\n\n\n<!-- end Post List -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4fe10c elementor-widget-tablet__width-inherit elementor-widget elementor-widget-ucaddon_archive_pagination\" data-id=\"c4fe10c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_archive_pagination.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Post Pagination -->\n\n<style>\/* widget: Post Pagination *\/\n\n#uc_archive_pagination_elementor_c4fe10c nav\n{\n  padding:0px;\n  margin:0px;\n}\n\n#uc_archive_pagination_elementor_c4fe10c \n{\n  display:flex;\n  flex-wrap: wrap;\n  justify-content:center;\n}\n\n#uc_archive_pagination_elementor_c4fe10c .nav-links\n{\n  display:flex;\n  justify-content:center;\n}\n\n#uc_archive_pagination_elementor_c4fe10c .nav-links > *\n{\n}\n\n#uc_archive_pagination_elementor_c4fe10c .page-numbers\n{\n  display:flex;\n  \n  align-items:center;\n  justify-content:center;\n  transition:0.3s;\n  line-height:1em;\n}\n\n\n#uc_archive_pagination_elementor_c4fe10c a.page-numbers, #uc_archive_pagination_elementor_c4fe10c .dots\n{\n  color:#000000;\n  background-color:;\n}\n\n#uc_archive_pagination_elementor_c4fe10c a.page-numbers:hover\n{\n  color:#6e6e6e;\n  background-color:#eeeeee;\n}\n\n#uc_archive_pagination_elementor_c4fe10c .page-numbers.current,\n#uc_archive_pagination_elementor_c4fe10c .page-numbers.current:hover\n{\n  background-color:#000000;\n  color:#ffffff;\n}\n\n\n#uc_archive_pagination_elementor_c4fe10c .page-numbers.prev, #uc_archive_pagination_elementor_c4fe10c .page-numbers.next\n{\n  padding-left:15px;\n  padding-right:15px;\n}\n\n\n\n#uc_archive_pagination_elementor_c4fe10c .prev:before {\n   font-family: \"Font Awesome 5 Free\";\n   content: \"\\f053\";\n   display: inline-block;\n   vertical-align: middle;\n   font-weight: 900;\n   padding-right:10px;}\n\n#uc_archive_pagination_elementor_c4fe10c .next:after {\n   font-family: \"Font Awesome 5 Free\";\n   content: \"\\f054\";\n   display: inline-block;\n   vertical-align: middle;\n   font-weight: 900;\n   padding-left:10px;}\n\n#uc_archive_pagination_elementor_c4fe10c.uc-ajax-loading{\n\topacity:1 !important;\n}\n\n#uc_archive_pagination_elementor_c4fe10c.uc-ajax-loading .current{\n\tposition:relative;\n    overflow:hidden;\n}\n\n\n#uc_archive_pagination_elementor_c4fe10c.uc-ajax-loading .current:before{\n  content: \"\";\n  display:block;\n  width:100%;\n  height:100%;\n  box-sizing:border-box;\n  position:absolute;\n  top:0px;\n  left:0px;\n  background-color: #c2c2c2;\n  animation: uc-spinning-border 0.5s linear infinite;\n  opacity:50%;\n  border-radius:inherit;\n}\n\n@keyframes uc-spinning-border {\n\t0%{transform: scale(0);}\n\t100%{transform: scale(1); }\t\n}\n\n\n\n<\/style>\n\n<div id=\"uc_archive_pagination_elementor_c4fe10c\" class=\"archive_pagination uc-filter-pagination\">\n<span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/2\/\" data-e-disable-page-transition=\"true\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/3\/\" data-e-disable-page-transition=\"true\">3<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/4\/\" data-e-disable-page-transition=\"true\">4<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/5\/\" data-e-disable-page-transition=\"true\">5<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/6\/\" data-e-disable-page-transition=\"true\">6<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/7\/\" data-e-disable-page-transition=\"true\">7<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/8\/\" data-e-disable-page-transition=\"true\">8<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/9\/\" data-e-disable-page-transition=\"true\">9<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/10\/\" data-e-disable-page-transition=\"true\">10<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/11\/\" data-e-disable-page-transition=\"true\">11<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/12\/\" data-e-disable-page-transition=\"true\">12<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/13\/\" data-e-disable-page-transition=\"true\">13<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/14\/\" data-e-disable-page-transition=\"true\">14<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/15\/\" data-e-disable-page-transition=\"true\">15<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/news-laufabteilung\/2\/\" data-e-disable-page-transition=\"true\">Next<\/a>\n<\/div>\n<!-- end Post Pagination -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47b1ae09 e-con-full e-flex e-con e-child\" data-id=\"47b1ae09\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-435f5add elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"435f5add\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5cf8eeee e-con-full e-flex e-con e-child\" data-id=\"5cf8eeee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1d46a872 e-con-full e-flex e-con e-child\" data-id=\"1d46a872\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a8ef3a7 elementor-widget elementor-widget-button\" data-id=\"7a8ef3a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/impressum\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Impressum<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-78bf0d40 e-con-full e-flex e-con e-child\" data-id=\"78bf0d40\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ece2422 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2ece2422\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/datenschutz\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Datenschutz<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c10b643 e-con-full e-flex e-con e-child\" data-id=\"6c10b643\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64ff4621 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"64ff4621\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ptsv-rosenheim.de\/index.php\/downloads\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Downloads<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>News Jakob Lange l\u00e4uft Halbmarathon-DM in Hamburg &#8211; Vereinsrekord! Noch vor 3 Wochen erfolgreich im Einsatz beim Sommer-Weltcup der Nordischen Kombinierer mit einem 3. Platz im Mixed-Team und 2. bester Laufzeit und Platz 14 im Einzel beim Weltcup in Oberstdorf. Jetzt&#8230; SwissPeaks 360 &#8222;There comes a time in a race like this when it feels [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","footnotes":""},"class_list":["post-1425","page","type-page","status-publish","hentry"],"blocksy_meta":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:26:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ptsv-rosenheim.de\/index.php\/wp-json\/wp\/v2\/pages\/1425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptsv-rosenheim.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ptsv-rosenheim.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ptsv-rosenheim.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ptsv-rosenheim.de\/index.php\/wp-json\/wp\/v2\/comments?post=1425"}],"version-history":[{"count":14,"href":"https:\/\/ptsv-rosenheim.de\/index.php\/wp-json\/wp\/v2\/pages\/1425\/revisions"}],"predecessor-version":[{"id":2426,"href":"https:\/\/ptsv-rosenheim.de\/index.php\/wp-json\/wp\/v2\/pages\/1425\/revisions\/2426"}],"wp:attachment":[{"href":"https:\/\/ptsv-rosenheim.de\/index.php\/wp-json\/wp\/v2\/media?parent=1425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}